
{"id":16759,"date":"2023-10-03T00:01:52","date_gmt":"2023-10-03T04:01:52","guid":{"rendered":"https:\/\/ctsq.qc.ca\/?page_id=16759"},"modified":"2023-10-03T00:01:52","modified_gmt":"2023-10-03T04:01:52","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<p class=\"p1\">Derni\u00e8re mise \u00e0 jour le 12 septembre 2023<\/p>\n<p class=\"p1\">Cet avis de confidentialit\u00e9 de La corporation des th\u00e9rapeutes du sport du Qu\u00e9bec Inc. (&#8220;nous&#8221;, &#8220;notre&#8221; ou &#8220;nos&#8221;), d\u00e9crit comment et pourquoi nous pouvons collecter, stocker, utiliser et\/ou partager (&#8220;traiter&#8221;) vos informations lorsque vous utilisez nos services (&#8220;Services&#8221;), par exemple lorsque vous.. :<\/p>\n<p class=\"p1\">Visitez notre site web \u00e0 l&#8217;adresse https:\/\/www.ctsq.qc.ca, ou tout autre site web qui renvoie au pr\u00e9sent avis de confidentialit\u00e9.<\/p>\n<p class=\"p1\">s&#8217;engager avec nous dans d&#8217;autres domaines connexes, y compris les ventes, le marketing ou les \u00e9v\u00e9nements<\/p>\n<p class=\"p1\">Vous avez des questions ou des inqui\u00e9tudes ? La lecture de cet avis de confidentialit\u00e9 vous aidera \u00e0 comprendre vos droits et vos choix en mati\u00e8re de protection de la vie priv\u00e9e. Si vous n&#8217;\u00eates pas d&#8217;accord avec nos politiques et pratiques, veuillez ne pas utiliser nos services. Si vous avez encore des questions ou des pr\u00e9occupations, veuillez nous contacter \u00e0 l&#8217;adresse suivante : rprp@ctsq.qc.ca.<\/p>\n<p class=\"p1\">R\u00c9SUM\u00c9 DES POINTS CL\u00c9S<\/p>\n<p class=\"p1\">Ce r\u00e9sum\u00e9 pr\u00e9sente les points cl\u00e9s de notre avis de confidentialit\u00e9, mais vous pouvez obtenir plus de d\u00e9tails sur chacun de ces sujets en cliquant sur le lien qui suit chaque point cl\u00e9 ou en utilisant notre table des mati\u00e8res ci-dessous pour trouver la section que vous recherchez.<\/p>\n<p class=\"p1\">Quelles informations personnelles traitons-nous ? Lorsque vous visitez, utilisez ou naviguez sur nos services, nous pouvons traiter des informations personnelles en fonction de la mani\u00e8re dont vous interagissez avec nous et les services, des choix que vous faites et des produits et fonctionnalit\u00e9s que vous utilisez. En savoir plus sur les informations personnelles que vous nous communiquez.<\/p>\n<p class=\"p1\">Traitons-nous des informations personnelles sensibles ? Nous pouvons traiter des informations personnelles sensibles lorsque cela est n\u00e9cessaire, avec votre consentement ou si la loi applicable le permet. En savoir plus sur les informations sensibles que nous traitons.<\/p>\n<p class=\"p1\">Recevons-nous des informations de la part de tiers ? Nous ne recevons aucune information de la part de tiers.<\/p>\n<p class=\"p1\">Comment traitons-nous vos informations ? Nous traitons vos informations pour fournir, am\u00e9liorer et administrer nos services, pour communiquer avec vous, pour la s\u00e9curit\u00e9 et la pr\u00e9vention de la fraude, et pour nous conformer \u00e0 la loi. Nous pouvons \u00e9galement traiter vos informations \u00e0 d&#8217;autres fins avec votre consentement. Nous ne traitons vos informations que lorsque nous avons une raison l\u00e9gale valable de le faire. En savoir plus sur la mani\u00e8re dont nous traitons vos informations.<\/p>\n<p class=\"p1\">Dans quelles situations et avec quels types de parties partageons-nous des informations personnelles ? Nous pouvons partager des informations dans des situations sp\u00e9cifiques et avec des cat\u00e9gories sp\u00e9cifiques de tiers. Pour en savoir plus sur les situations dans lesquelles nous partageons vos informations personnelles et les personnes avec lesquelles nous le faisons.<\/p>\n<p class=\"p1\">Comment assurons-nous la s\u00e9curit\u00e9 de vos informations ? Nous avons mis en place des processus et des proc\u00e9dures organisationnels et techniques pour prot\u00e9ger vos informations personnelles. Toutefois, aucune transmission \u00e9lectronique sur l&#8217;internet ou technologie de stockage des informations ne peut \u00eatre garantie \u00e0 100 %. Nous ne pouvons donc pas promettre ou garantir que des pirates informatiques, des cybercriminels ou d&#8217;autres tiers non autoris\u00e9s ne seront pas en mesure de d\u00e9jouer notre s\u00e9curit\u00e9 et de collecter, d&#8217;acc\u00e9der, de voler ou de modifier vos informations de mani\u00e8re inappropri\u00e9e. En savoir plus sur la mani\u00e8re dont nous assurons la s\u00e9curit\u00e9 de vos informations.<\/p>\n<p class=\"p1\">Quels sont vos droits ? En fonction de votre situation g\u00e9ographique, la l\u00e9gislation applicable en mati\u00e8re de protection de la vie priv\u00e9e peut vous conf\u00e9rer certains droits concernant vos informations personnelles. En savoir plus sur vos droits en mati\u00e8re de protection de la vie priv\u00e9e.<\/p>\n<p class=\"p1\">Comment exercer vos droits ? La mani\u00e8re la plus simple d&#8217;exercer vos droits est de visiter le site rprp@ctsq.qc.ca ou de nous contacter. Nous examinerons toute demande et y donnerons suite conform\u00e9ment aux lois applicables en mati\u00e8re de protection des donn\u00e9es.<\/p>\n<p class=\"p1\">Vous voulez en savoir plus sur ce que nous faisons des informations que nous recueillons ? Consultez l&#8217;avis de confidentialit\u00e9 dans son int\u00e9gralit\u00e9.<\/p>\n<p class=\"p1\">TABLE DES MATI\u00c8RES<\/p>\n<p class=\"p1\">1. QUELLES SONT LES INFORMATIONS QUE NOUS RECUEILLONS ?<\/p>\n<p class=\"p1\">2. COMMENT TRAITONS-NOUS VOS INFORMATIONS ?<\/p>\n<p class=\"p1\">3. SUR QUELLES BASES JURIDIQUES NOUS APPUYONS-NOUS POUR TRAITER VOS INFORMATIONS PERSONNELLES ?<\/p>\n<p class=\"p1\">4. QUAND ET AVEC QUI PARTAGEONS-NOUS VOS INFORMATIONS PERSONNELLES ?<\/p>\n<p class=\"p1\">5. UTILISONS-NOUS DES COOKIES ET D&#8217;AUTRES TECHNOLOGIES DE SUIVI ?<\/p>\n<p class=\"p1\">6. COMBIEN DE TEMPS CONSERVONS-NOUS VOS INFORMATIONS ?<\/p>\n<p class=\"p1\">7. COMMENT ASSURONS-NOUS LA S\u00c9CURIT\u00c9 DE VOS INFORMATIONS ?<\/p>\n<p class=\"p1\">8. QUELS SONT VOS DROITS EN MATI\u00c8RE DE PROTECTION DE LA VIE PRIV\u00c9E ?<\/p>\n<p class=\"p1\">9. CONTR\u00d4LES POUR LES DISPOSITIFS &#8220;DO-NOT-TRACK&#8221; (NE PAS SUIVRE)<\/p>\n<p class=\"p1\">10. LES R\u00c9SIDENTS DE CALIFORNIE ONT-ILS DES DROITS SP\u00c9CIFIQUES EN MATI\u00c8RE DE PROTECTION DE LA VIE PRIV\u00c9E ?<\/p>\n<p class=\"p1\">11. LE PR\u00c9SENT AVIS FAIT-IL L&#8217;OBJET DE MISES \u00c0 JOUR ?<\/p>\n<p class=\"p1\">12. COMMENT POUVEZ-VOUS NOUS CONTACTER AU SUJET DE CET AVIS ?<\/p>\n<p class=\"p1\">13. COMMENT POUVEZ-VOUS CONSULTER, METTRE \u00c0 JOUR OU SUPPRIMER LES DONN\u00c9ES QUE NOUS COLLECTONS AUPR\u00c8S DE VOUS ?<\/p>\n<p class=\"p1\">1. QUELLES SONT LES INFORMATIONS QUE NOUS RECUEILLONS ?<\/p>\n<p class=\"p1\">Informations personnelles que vous nous communiquez<\/p>\n<p class=\"p1\">En bref : nous recueillons les informations personnelles que vous nous fournissez.<\/p>\n<p class=\"p1\">Nous recueillons les informations personnelles que vous nous fournissez volontairement lorsque vous vous inscrivez sur les services, lorsque vous souhaitez obtenir des informations sur nous ou sur nos produits et services, lorsque vous participez \u00e0 des activit\u00e9s sur les services, ou encore lorsque vous nous contactez.<\/p>\n<p class=\"p1\">Informations personnelles fournies par vous. Les informations personnelles que nous recueillons d\u00e9pendent du contexte de vos interactions avec nous et les services, des choix que vous faites et des produits et fonctions que vous utilisez. Les informations personnelles que nous recueillons peuvent comprendre les \u00e9l\u00e9ments suivants :<\/p>\n<p class=\"p1\">noms<\/p>\n<p class=\"p1\">num\u00e9ros de t\u00e9l\u00e9phone<\/p>\n<p class=\"p1\">adresses \u00e9lectroniques<\/p>\n<p class=\"p1\">adresses postales<\/p>\n<p class=\"p1\">titres de postes<\/p>\n<p class=\"p1\">pr\u00e9f\u00e9rences de contact<\/p>\n<p class=\"p1\">les num\u00e9ros de cartes de d\u00e9bit\/cr\u00e9dit<\/p>\n<p class=\"p1\">les adresses de facturation<\/p>\n<p class=\"p1\">mots de passe<\/p>\n<p class=\"p1\">noms d&#8217;utilisateur<\/p>\n<p class=\"p1\">Informations sensibles. Lorsque cela est n\u00e9cessaire, avec votre consentement ou dans la mesure o\u00f9 la l\u00e9gislation applicable le permet, nous traitons les cat\u00e9gories suivantes d&#8217;informations sensibles :<\/p>\n<p class=\"p1\">Donn\u00e9es de paiement. Nous pouvons collecter les donn\u00e9es n\u00e9cessaires au traitement de votre paiement si vous effectuez des achats, telles que votre num\u00e9ro d&#8217;instrument de paiement et le code de s\u00e9curit\u00e9 associ\u00e9 \u00e0 votre instrument de paiement. Toutes les donn\u00e9es de paiement sont stock\u00e9es par Paypal et Square. Vous pouvez consulter leurs avis de confidentialit\u00e9 en cliquant sur les liens suivants : https:\/\/www.paypal.com\/us\/legalhub\/privacy-full et https:\/\/squareup.com\/help\/ca\/fr\/article\/3796-privacy-and-security.<\/p>\n<p class=\"p1\">Toutes les informations personnelles que vous nous fournissez doivent \u00eatre vraies, compl\u00e8tes et exactes, et vous devez nous informer de toute modification de ces informations personnelles.<\/p>\n<p class=\"p1\">Informations collect\u00e9es automatiquement<\/p>\n<p class=\"p1\">En bref : Certaines informations &#8211; telles que votre adresse de protocole Internet (IP) et\/ou les caract\u00e9ristiques de votre navigateur et de votre appareil &#8211; sont collect\u00e9es automatiquement lorsque vous visitez nos services.<\/p>\n<p class=\"p1\">Nous recueillons automatiquement certaines informations lorsque vous visitez, utilisez ou naviguez sur les services. Ces informations ne r\u00e9v\u00e8lent pas votre identit\u00e9 sp\u00e9cifique (comme votre nom ou vos coordonn\u00e9es) mais peuvent inclure des informations sur votre appareil et votre utilisation, comme votre adresse IP, les caract\u00e9ristiques de votre navigateur et de votre appareil, votre syst\u00e8me d&#8217;exploitation, vos pr\u00e9f\u00e9rences linguistiques, les URL de r\u00e9f\u00e9rence, le nom de votre appareil, votre pays, votre localisation, des informations sur la mani\u00e8re dont vous utilisez nos services et sur le moment o\u00f9 vous les utilisez, ainsi que d&#8217;autres informations techniques. Ces informations sont principalement n\u00e9cessaires pour maintenir la s\u00e9curit\u00e9 et le fonctionnement de nos services, ainsi qu&#8217;\u00e0 des fins d&#8217;analyse et de rapport internes.<\/p>\n<p class=\"p1\">Comme de nombreuses entreprises, nous recueillons \u00e9galement des informations par le biais de cookies et de technologies similaires.<\/p>\n<p class=\"p1\">Les informations que nous recueillons sont les suivantes :<\/p>\n<p class=\"p1\">Donn\u00e9es de connexion et d&#8217;utilisation. Les donn\u00e9es de connexion et d&#8217;utilisation sont des informations relatives au service, au diagnostic, \u00e0 l&#8217;utilisation et \u00e0 la performance que nos serveurs collectent automatiquement lorsque vous acc\u00e9dez \u00e0 nos services ou les utilisez et que nous enregistrons dans des fichiers de connexion. Selon la mani\u00e8re dont vous interagissez avec nous, ces donn\u00e9es de journal peuvent inclure votre adresse IP, des informations sur votre appareil, votre type de navigateur et vos param\u00e8tres, ainsi que des informations sur votre activit\u00e9 dans les services (telles que les horodatages associ\u00e9s \u00e0 votre utilisation, les pages et les fichiers consult\u00e9s, les recherches et les autres actions que vous effectuez, telles que les fonctions que vous utilisez), des informations sur les \u00e9v\u00e9nements de l&#8217;appareil (telles que l&#8217;activit\u00e9 du syst\u00e8me, les rapports d&#8217;erreur (parfois appel\u00e9s &#8220;crash dumps&#8221;) et les param\u00e8tres du mat\u00e9riel).<\/p>\n<p class=\"p1\">Donn\u00e9es relatives \u00e0 l&#8217;appareil. Nous collectons des donn\u00e9es sur les appareils, telles que des informations sur votre ordinateur, votre t\u00e9l\u00e9phone, votre tablette ou tout autre appareil que vous utilisez pour acc\u00e9der aux services. En fonction de l&#8217;appareil utilis\u00e9, ces donn\u00e9es peuvent inclure des informations telles que votre adresse IP (ou serveur proxy), les num\u00e9ros d&#8217;identification de l&#8217;appareil et de l&#8217;application, la localisation, le type de navigateur, le mod\u00e8le de mat\u00e9riel, le fournisseur d&#8217;acc\u00e8s Internet et\/ou l&#8217;op\u00e9rateur mobile, le syst\u00e8me d&#8217;exploitation et les informations relatives \u00e0 la configuration du syst\u00e8me.<\/p>\n<p class=\"p1\">Donn\u00e9es de localisation. Nous collectons des donn\u00e9es de localisation telles que des informations sur l&#8217;emplacement de votre appareil, qui peuvent \u00eatre pr\u00e9cises ou impr\u00e9cises. La quantit\u00e9 d&#8217;informations collect\u00e9es d\u00e9pend du type et des param\u00e8tres de l&#8217;appareil que vous utilisez pour acc\u00e9der aux services. Par exemple, nous pouvons utiliser le GPS et d&#8217;autres technologies pour collecter des donn\u00e9es de g\u00e9olocalisation qui nous indiquent votre emplacement actuel (sur la base de votre adresse IP). Vous pouvez choisir de ne pas nous autoriser \u00e0 collecter ces informations, soit en refusant l&#8217;acc\u00e8s \u00e0 ces informations, soit en d\u00e9sactivant les param\u00e8tres de localisation de votre appareil. Toutefois, si vous choisissez de vous d\u00e9sengager, il se peut que vous ne puissiez pas utiliser certains aspects des services.<\/p>\n<p class=\"p1\">2. COMMENT TRAITONS-NOUS VOS INFORMATIONS ?<\/p>\n<p class=\"p1\">En bref : nous traitons vos informations pour fournir, am\u00e9liorer et g\u00e9rer nos services, communiquer avec vous, pour la s\u00e9curit\u00e9 et la pr\u00e9vention de la fraude, et pour nous conformer \u00e0 la loi. Nous pouvons \u00e9galement traiter vos informations \u00e0 d&#8217;autres fins avec votre consentement.<\/p>\n<p class=\"p1\">Nous traitons vos informations personnelles pour diverses raisons, en fonction de la mani\u00e8re dont vous interagissez avec nos services, notamment :<\/p>\n<p class=\"p1\">Faciliter la cr\u00e9ation et l&#8217;authentification des comptes et g\u00e9rer les comptes des utilisateurs. Nous pouvons traiter vos informations afin que vous puissiez cr\u00e9er votre compte et vous y connecter, ainsi que pour maintenir votre compte en bon \u00e9tat de fonctionnement.<\/p>\n<p class=\"p1\">Fournir et faciliter la fourniture de services \u00e0 l&#8217;utilisateur. Nous pouvons traiter vos informations pour vous fournir le service demand\u00e9.<\/p>\n<p class=\"p1\">R\u00e9pondre aux demandes des utilisateurs\/offrir une assistance aux utilisateurs. Nous pouvons traiter vos informations pour r\u00e9pondre \u00e0 vos demandes et r\u00e9soudre tout probl\u00e8me potentiel que vous pourriez avoir avec le service demand\u00e9.<\/p>\n<p class=\"p1\">Pour ex\u00e9cuter et g\u00e9rer vos commandes. Nous pouvons traiter vos informations pour ex\u00e9cuter et g\u00e9rer vos commandes, paiements, retours et \u00e9changes effectu\u00e9s par l&#8217;interm\u00e9diaire des services.<\/p>\n<p class=\"p1\">Pour \u00e9valuer et am\u00e9liorer nos services, nos produits, notre marketing et votre exp\u00e9rience. Nous pouvons traiter vos informations lorsque nous le jugeons n\u00e9cessaire pour identifier les tendances d&#8217;utilisation, d\u00e9terminer l&#8217;efficacit\u00e9 de nos campagnes promotionnelles et \u00e9valuer et am\u00e9liorer nos services, nos produits, notre marketing et votre exp\u00e9rience.<\/p>\n<p class=\"p1\">Pour se conformer \u00e0 nos obligations l\u00e9gales. Nous pouvons traiter vos informations pour nous conformer \u00e0 nos obligations l\u00e9gales, r\u00e9pondre \u00e0 des demandes l\u00e9gales et exercer, \u00e9tablir ou d\u00e9fendre nos droits l\u00e9gaux.<\/p>\n<p class=\"p1\">3. SUR QUELLES BASES JURIDIQUES NOUS APPUYONS-NOUS POUR TRAITER VOS INFORMATIONS ?<\/p>\n<p class=\"p1\">En bref : nous ne traitons vos informations personnelles que lorsque nous estimons que cela est n\u00e9cessaire et que nous avons une raison juridique valable (c&#8217;est-\u00e0-dire une base juridique) de le faire en vertu du droit applicable, par exemple avec votre consentement, pour nous conformer \u00e0 la l\u00e9gislation, pour vous fournir des services, pour nous acquitter de nos obligations contractuelles, pour prot\u00e9ger vos droits ou pour r\u00e9pondre \u00e0 nos int\u00e9r\u00eats commerciaux l\u00e9gitimes.<\/p>\n<p class=\"p1\">Nous pouvons traiter vos informations si vous nous avez donn\u00e9 l&#8217;autorisation sp\u00e9cifique (c&#8217;est-\u00e0-dire le consentement explicite) d&#8217;utiliser vos informations personnelles \u00e0 des fins sp\u00e9cifiques, ou dans des situations o\u00f9 votre autorisation peut \u00eatre d\u00e9duite (c&#8217;est-\u00e0-dire le consentement implicite). Vous pouvez retirer votre consentement \u00e0 tout moment.<\/p>\n<p class=\"p1\">Dans certains cas exceptionnels, nous pouvons \u00eatre l\u00e9galement autoris\u00e9s, en vertu de la loi applicable, \u00e0 traiter vos informations sans votre consentement, y compris, par exemple :<\/p>\n<p class=\"p1\">Si la collecte est clairement dans l&#8217;int\u00e9r\u00eat d&#8217;une personne et que le consentement ne peut \u00eatre obtenu en temps utile<\/p>\n<p class=\"p1\">Pour les enqu\u00eates et la d\u00e9tection et la pr\u00e9vention de la fraude<\/p>\n<p class=\"p1\">Pour les transactions commerciales, sous r\u00e9serve que certaines conditions soient remplies<\/p>\n<p class=\"p1\">S&#8217;il est contenu dans une d\u00e9claration de t\u00e9moin et que la collecte est n\u00e9cessaire pour \u00e9valuer, traiter ou r\u00e9gler une demande d&#8217;indemnisation.<\/p>\n<p class=\"p1\">Pour identifier les personnes bless\u00e9es, malades ou d\u00e9c\u00e9d\u00e9es et communiquer avec leurs proches<\/p>\n<p class=\"p1\">Si nous avons des motifs raisonnables de croire qu&#8217;une personne a \u00e9t\u00e9, est ou pourrait \u00eatre victime d&#8217;un abus financier<\/p>\n<p class=\"p1\">S&#8217;il est raisonnable de penser que la collecte et l&#8217;utilisation avec le consentement compromettraient la disponibilit\u00e9 ou l&#8217;exactitude des informations et que la collecte est raisonnable \u00e0 des fins li\u00e9es \u00e0 une enqu\u00eate sur une violation d&#8217;un accord ou une contravention au droit du Canada ou d&#8217;une province.<\/p>\n<p class=\"p1\">Si la divulgation est n\u00e9cessaire pour se conformer \u00e0 une citation \u00e0 compara\u00eetre, \u00e0 un mandat, \u00e0 une ordonnance du tribunal ou aux r\u00e8gles du tribunal relatives \u00e0 la production de documents<\/p>\n<p class=\"p1\">si elles ont \u00e9t\u00e9 produites par une personne dans le cadre de son emploi, de son entreprise ou de sa profession et que la collecte est compatible avec les objectifs pour lesquels les informations ont \u00e9t\u00e9 produites<\/p>\n<p class=\"p1\">Si la collection est uniquement destin\u00e9e \u00e0 des fins journalistiques, artistiques ou litt\u00e9raires<\/p>\n<p class=\"p1\">Si l&#8217;information est accessible au public et est sp\u00e9cifi\u00e9e par les r\u00e8glements<\/p>\n<p class=\"p1\">4. QUAND ET AVEC QUI PARTAGEONS-NOUS VOS INFORMATIONS PERSONNELLES ?<\/p>\n<p class=\"p1\">En bref : nous pouvons partager des informations dans des situations sp\u00e9cifiques d\u00e9crites dans cette section et\/ou avec les cat\u00e9gories de tiers suivantes.<\/p>\n<p class=\"p1\">Fournisseurs, consultants et autres prestataires de services tiers. Nous pouvons partager vos donn\u00e9es avec des vendeurs, des prestataires de services, des contractants ou des agents tiers (&#8220;tiers&#8221;) qui fournissent des services pour nous ou en notre nom et qui ont besoin d&#8217;acc\u00e9der \u00e0 ces informations pour effectuer leur travail. Les cat\u00e9gories de tiers avec lesquels nous pouvons partager des informations personnelles sont les suivantes :<\/p>\n<p class=\"p1\">Processeurs de paiement<\/p>\n<p class=\"p1\">Nous pouvons \u00e9galement \u00eatre amen\u00e9s \u00e0 partager vos informations personnelles dans les situations suivantes :<\/p>\n<p class=\"p1\">Transferts d&#8217;entreprise. Nous pouvons partager ou transf\u00e9rer vos informations dans le cadre d&#8217;une fusion, d&#8217;une vente d&#8217;actifs de la soci\u00e9t\u00e9, d&#8217;un financement ou d&#8217;une acquisition de tout ou partie de nos activit\u00e9s \u00e0 une autre soci\u00e9t\u00e9, ou pendant les n\u00e9gociations relatives \u00e0 une telle op\u00e9ration.<\/p>\n<p class=\"p1\">5. UTILISONS-NOUS DES COOKIES ET D&#8217;AUTRES TECHNOLOGIES DE SUIVI ?<\/p>\n<p class=\"p1\">En bref : Nous pouvons utiliser des cookies et d&#8217;autres technologies de suivi pour collecter et stocker vos informations.<\/p>\n<p class=\"p1\">Nous pouvons utiliser des cookies et des technologies de suivi similaires (comme les balises web et les pixels) pour acc\u00e9der \u00e0 des informations ou les stocker. Des informations sp\u00e9cifiques sur la mani\u00e8re dont nous utilisons ces technologies et sur la mani\u00e8re dont vous pouvez refuser certains cookies sont pr\u00e9sent\u00e9es dans notre avis sur les cookies.<\/p>\n<p class=\"p1\">6. COMBIEN DE TEMPS CONSERVONS-NOUS VOS INFORMATIONS ?<\/p>\n<p class=\"p1\">En bref : nous conservons vos informations aussi longtemps que n\u00e9cessaire pour atteindre les objectifs d\u00e9crits dans le pr\u00e9sent avis de confidentialit\u00e9, \u00e0 moins que la loi n&#8217;en dispose autrement.<\/p>\n<p class=\"p1\">Nous ne conserverons vos donn\u00e9es personnelles qu&#8217;aussi longtemps que n\u00e9cessaire aux fins \u00e9nonc\u00e9es dans le pr\u00e9sent avis de confidentialit\u00e9, \u00e0 moins qu&#8217;une p\u00e9riode de conservation plus longue ne soit requise ou autoris\u00e9e par la loi (par exemple, pour des raisons fiscales, comptables ou d&#8217;autres exigences l\u00e9gales). Aucune des finalit\u00e9s \u00e9nonc\u00e9es dans le pr\u00e9sent avis n&#8217;exige que nous conservions vos informations personnelles plus longtemps que la p\u00e9riode pendant laquelle les utilisateurs disposent d&#8217;un compte chez nous.<\/p>\n<p class=\"p1\">Lorsque nous n&#8217;avons plus de besoin commercial l\u00e9gitime de traiter vos informations personnelles, nous les supprimons ou les rendons anonymes ou, si cela n&#8217;est pas possible (par exemple, parce que vos informations personnelles ont \u00e9t\u00e9 stock\u00e9es dans des archives de sauvegarde), nous les conservons en toute s\u00e9curit\u00e9 et les isolons de tout traitement ult\u00e9rieur jusqu&#8217;\u00e0 ce que leur suppression soit possible.<\/p>\n<p class=\"p1\">7. COMMENT ASSURONS-NOUS LA S\u00c9CURIT\u00c9 DE VOS INFORMATIONS ?<\/p>\n<p class=\"p1\">En bref : nous visons \u00e0 prot\u00e9ger vos informations personnelles gr\u00e2ce \u00e0 un syst\u00e8me de mesures de s\u00e9curit\u00e9 organisationnelles et techniques.<\/p>\n<p class=\"p1\">Nous avons mis en \u0153uvre des mesures de s\u00e9curit\u00e9 techniques et organisationnelles appropri\u00e9es et raisonnables con\u00e7ues pour prot\u00e9ger la s\u00e9curit\u00e9 de toute information personnelle que nous traitons. Toutefois, malgr\u00e9 nos mesures de protection et nos efforts pour s\u00e9curiser vos informations, aucune transmission \u00e9lectronique sur l&#8217;internet ou technologie de stockage de l&#8217;information ne peut \u00eatre garantie \u00e0 100 %, de sorte que nous ne pouvons pas promettre ou garantir que les pirates informatiques, les cybercriminels ou d&#8217;autres tiers non autoris\u00e9s ne seront pas en mesure de d\u00e9jouer notre s\u00e9curit\u00e9 et de collecter, d&#8217;acc\u00e9der, de voler ou de modifier vos informations de mani\u00e8re inappropri\u00e9e. Bien que nous fassions de notre mieux pour prot\u00e9ger vos informations personnelles, la transmission d&#8217;informations personnelles vers et \u00e0 partir de nos services se fait \u00e0 vos propres risques. Vous ne devez acc\u00e9der aux services que dans un environnement s\u00e9curis\u00e9.<\/p>\n<p class=\"p1\">8. QUELS SONT VOS DROITS EN MATI\u00c8RE DE PROTECTION DE LA VIE PRIV\u00c9E ?<\/p>\n<p class=\"p1\">En bref : dans certaines r\u00e9gions, comme le Canada, vous avez des droits qui vous permettent d&#8217;acc\u00e9der plus facilement \u00e0 vos informations personnelles et de les contr\u00f4ler. Vous pouvez \u00e0 tout moment consulter, modifier ou r\u00e9silier votre compte.<\/p>\n<p class=\"p1\">Dans certaines r\u00e9gions (comme le Canada), vous disposez de certains droits en vertu des lois applicables en mati\u00e8re de protection des donn\u00e9es. Il peut s&#8217;agir du droit (i) de demander l&#8217;acc\u00e8s \u00e0 vos informations personnelles et d&#8217;en obtenir une copie, (ii) de demander la rectification ou l&#8217;effacement, (iii) de restreindre le traitement de vos informations personnelles, (vi) le cas \u00e9ch\u00e9ant, de b\u00e9n\u00e9ficier de la portabilit\u00e9 des donn\u00e9es, et (vii) de ne pas faire l&#8217;objet d&#8217;une prise de d\u00e9cision automatis\u00e9e. Dans certaines circonstances, vous pouvez \u00e9galement avoir le droit de vous opposer au traitement de vos informations personnelles. Vous pouvez faire une telle demande en nous contactant aux coordonn\u00e9es indiqu\u00e9es dans la section &#8220;COMMENT PEUT-ON NOUS CONTACTER AU SUJET DE LA PR\u00c9SENTE NOTICE&#8221; ci-dessous.<\/p>\n<p class=\"p1\">Nous examinerons toute demande et y donnerons suite conform\u00e9ment aux lois applicables en mati\u00e8re de protection des donn\u00e9es.<\/p>\n<p class=\"p1\">Retrait du consentement : Si nous nous appuyons sur votre consentement pour traiter vos informations personnelles, qui peut \u00eatre un consentement explicite et\/ou implicite en fonction de la loi applicable, vous avez le droit de retirer votre consentement \u00e0 tout moment. Vous pouvez retirer votre consentement \u00e0 tout moment en nous contactant aux coordonn\u00e9es indiqu\u00e9es dans la section &#8220;COMMENT PEUT-ON NOUS CONTACTER AU SUJET DE LA PR\u00c9SENTE NOTICE ?<\/p>\n<p class=\"p1\">Toutefois, veuillez noter que cela n&#8217;affectera pas la l\u00e9galit\u00e9 du traitement avant son retrait ni, lorsque la loi applicable le permet, le traitement de vos informations personnelles effectu\u00e9 sur la base de motifs de traitement l\u00e9gitimes autres que le consentement.<\/p>\n<p class=\"p1\">D\u00e9sinscription des communications marketing et promotionnelles : Vous pouvez vous d\u00e9sinscrire de nos communications marketing et promotionnelles \u00e0 tout moment en cliquant sur le lien de d\u00e9sinscription figurant dans les courriels que nous envoyons, ou en nous contactant aux coordonn\u00e9es indiqu\u00e9es dans la section &#8220;COMMENT PEUT-ON NOUS CONTACTER AU SUJET DE CET AVIS ? Vous serez alors retir\u00e9 des listes de marketing. Toutefois, nous pourrons continuer \u00e0 communiquer avec vous, par exemple pour vous envoyer des messages relatifs aux services n\u00e9cessaires \u00e0 l&#8217;administration et \u00e0 l&#8217;utilisation de votre compte, pour r\u00e9pondre \u00e0 des demandes de service ou \u00e0 d&#8217;autres fins non commerciales.<\/p>\n<p class=\"p1\">Informations sur le compte<\/p>\n<p class=\"p1\">Si vous souhaitez \u00e0 tout moment revoir ou modifier les informations contenues dans votre compte ou r\u00e9silier votre compte, vous pouvez le faire :<\/p>\n<p class=\"p1\">Contactez-nous en utilisant les coordonn\u00e9es fournies.<\/p>\n<p class=\"p1\">Si vous demandez la cl\u00f4ture de votre compte, nous d\u00e9sactiverons ou supprimerons votre compte et vos informations de nos bases de donn\u00e9es actives. Toutefois, nous pouvons conserver certaines informations dans nos fichiers afin de pr\u00e9venir la fraude, de r\u00e9soudre des probl\u00e8mes, de contribuer \u00e0 des enqu\u00eates, de faire respecter nos conditions l\u00e9gales et\/ou de nous conformer aux exigences l\u00e9gales applicables.<\/p>\n<p class=\"p1\">Cookies et technologies similaires : La plupart des navigateurs Web sont configur\u00e9s pour accepter les cookies par d\u00e9faut. Si vous pr\u00e9f\u00e9rez, vous pouvez g\u00e9n\u00e9ralement choisir de configurer votre navigateur pour qu&#8217;il supprime les cookies et les rejette. Si vous choisissez de supprimer les cookies ou de les rejeter, cela pourrait affecter certaines fonctionnalit\u00e9s ou certains services de nos services. Vous pouvez \u00e9galement choisir de ne pas recevoir de publicit\u00e9 bas\u00e9e sur les int\u00e9r\u00eats de la part des annonceurs sur nos services.<\/p>\n<p class=\"p1\">Si vous avez des questions ou des commentaires sur vos droits en mati\u00e8re de protection de la vie priv\u00e9e, vous pouvez nous envoyer un courrier \u00e9lectronique \u00e0 l&#8217;adresse rprp@ctsq.qc.ca.<\/p>\n<p class=\"p1\">9. CONTR\u00d4LES POUR LES DISPOSITIFS &#8220;DO-NOT-TRACK&#8221; (NE PAS SUIVRE)<\/p>\n<p class=\"p1\">La plupart des navigateurs web et certains syst\u00e8mes d&#8217;exploitation mobiles et applications mobiles comprennent une fonction ou un param\u00e8tre &#8220;Do-Not-Track&#8221; (&#8220;DNT&#8221;) que vous pouvez activer pour signaler votre pr\u00e9f\u00e9rence en mati\u00e8re de protection de la vie priv\u00e9e, \u00e0 savoir que les donn\u00e9es relatives \u00e0 vos activit\u00e9s de navigation en ligne ne doivent pas \u00eatre surveill\u00e9es et collect\u00e9es. \u00c0 ce stade, aucune norme technologique uniforme pour la reconnaissance et la mise en \u0153uvre des signaux DNT n&#8217;a \u00e9t\u00e9 finalis\u00e9e. Par cons\u00e9quent, nous ne r\u00e9pondons pas actuellement aux signaux DNT du navigateur ou \u00e0 tout autre m\u00e9canisme qui communique automatiquement votre choix de ne pas \u00eatre suivi en ligne. Si une norme de suivi en ligne est adopt\u00e9e et que nous devons la respecter \u00e0 l&#8217;avenir, nous vous informerons de cette pratique dans une version r\u00e9vis\u00e9e du pr\u00e9sent avis de confidentialit\u00e9.<\/p>\n<p class=\"p1\">10. LE PR\u00c9SENT AVIS FAIT-IL L&#8217;OBJET DE MISES \u00c0 JOUR ?<\/p>\n<p class=\"p1\">En bref : Oui, nous mettrons \u00e0 jour cet avis si n\u00e9cessaire pour rester en conformit\u00e9 avec les lois en vigueur.<\/p>\n<p class=\"p1\">Nous pouvons mettre \u00e0 jour le pr\u00e9sent avis de confidentialit\u00e9 de temps \u00e0 autre. La version mise \u00e0 jour sera indiqu\u00e9e par une date de mise \u00e0 jour &#8220;R\u00e9vis\u00e9&#8221; et la version mise \u00e0 jour sera effective d\u00e8s qu&#8217;elle sera accessible. Si nous apportons des modifications importantes au pr\u00e9sent avis de confidentialit\u00e9, nous vous en informerons soit en affichant de mani\u00e8re visible un avis de ces modifications, soit en vous envoyant directement une notification. Nous vous encourageons \u00e0 consulter r\u00e9guli\u00e8rement le pr\u00e9sent avis de confidentialit\u00e9 afin de vous tenir inform\u00e9 de la mani\u00e8re dont nous prot\u00e9geons vos informations.<\/p>\n<p class=\"p1\">11. COMMENT POUVEZ-VOUS NOUS CONTACTER AU SUJET DE CET AVIS ?<\/p>\n<p class=\"p1\">Si vous avez des questions ou des commentaires sur le pr\u00e9sent avis, vous pouvez nous envoyer un courriel \u00e0 l&#8217;adresse rprp@ctsq.qc.ca ou nous contacter par courrier \u00e0 l&#8217;adresse suivante :<\/p>\n<p class=\"p1\">\u00c9ric Grenier-Denis<\/p>\n<p class=\"p1\">Responsable de la protection des renseignements personnels<\/p>\n<p class=\"p1\">La corporation des th\u00e9rapeutes du sport du Qu\u00e9bec Inc.<\/p>\n<p class=\"p1\">C.P 884 Succ. Desjardins<\/p>\n<p class=\"p1\">Montr\u00e9al, Qu\u00e9bec H5B 1B9<\/p>\n<p class=\"p1\">Canada<\/p>\n<p class=\"p1\">12. COMMENT POUVEZ-VOUS CONSULTER, METTRE \u00c0 JOUR OU SUPPRIMER LES DONN\u00c9ES QUE NOUS COLLECTONS AUPR\u00c8S DE VOUS ?<\/p>\n<p class=\"p1\">En fonction des lois applicables dans votre pays, vous pouvez avoir le droit de demander l&#8217;acc\u00e8s aux informations personnelles que nous recueillons aupr\u00e8s de vous, de modifier ces informations ou de les supprimer. Pour demander la r\u00e9vision, la mise \u00e0 jour ou la suppression de vos informations personnelles, veuillez contacter notre responsable de la protection des renseignements personnels au courriel suivant: rprp@ctsq.qc.ca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Derni\u00e8re mise \u00e0 jour le 12 septembre 2023 Cet avis de confidentialit\u00e9 de La corporation des th\u00e9rapeutes du sport du Qu\u00e9bec Inc. (&#8220;nous&#8221;, &#8220;notre&#8221; ou &#8220;nos&#8221;), d\u00e9crit comment et pourquoi nous pouvons collecter, stocker, utiliser et\/ou partager (&#8220;traiter&#8221;) vos informations lorsque vous utilisez nos services (&#8220;Services&#8221;), par exemple lorsque vous.. : Visitez notre site web [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"pmpro_default_level":0,"footnotes":""},"class_list":["post-16759","page","type-page","status-publish","hentry","pmpro-has-access"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy - CTSQ<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy - CTSQ\" \/>\n<meta property=\"og:description\" content=\"Derni\u00e8re mise \u00e0 jour le 12 septembre 2023 Cet avis de confidentialit\u00e9 de La corporation des th\u00e9rapeutes du sport du Qu\u00e9bec Inc. (&#8220;nous&#8221;, &#8220;notre&#8221; ou &#8220;nos&#8221;), d\u00e9crit comment et pourquoi nous pouvons collecter, stocker, utiliser et\/ou partager (&#8220;traiter&#8221;) vos informations lorsque vous utilisez nos services (&#8220;Services&#8221;), par exemple lorsque vous.. : Visitez notre site web [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"CTSQ\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - CTSQ\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/#website\"},\"datePublished\":\"2023-10-03T04:01:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/\",\"name\":\"CTSQ\",\"description\":\"La corporation des th\u00e9rapeutes du sport du Qu\u00e9bec\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ctsq.qc.ca\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy Policy - CTSQ","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/","og_locale":"en_US","og_type":"article","og_title":"Privacy Policy - CTSQ","og_description":"Derni\u00e8re mise \u00e0 jour le 12 septembre 2023 Cet avis de confidentialit\u00e9 de La corporation des th\u00e9rapeutes du sport du Qu\u00e9bec Inc. (&#8220;nous&#8221;, &#8220;notre&#8221; ou &#8220;nos&#8221;), d\u00e9crit comment et pourquoi nous pouvons collecter, stocker, utiliser et\/ou partager (&#8220;traiter&#8221;) vos informations lorsque vous utilisez nos services (&#8220;Services&#8221;), par exemple lorsque vous.. : Visitez notre site web [&hellip;]","og_url":"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/","og_site_name":"CTSQ","twitter_misc":{"Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/","url":"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/","name":"Privacy Policy - CTSQ","isPartOf":{"@id":"https:\/\/ctsq.qc.ca\/en\/#website"},"datePublished":"2023-10-03T04:01:52+00:00","breadcrumb":{"@id":"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ctsq.qc.ca\/en\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ctsq.qc.ca\/en\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ctsq.qc.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/ctsq.qc.ca\/en\/#website","url":"https:\/\/ctsq.qc.ca\/en\/","name":"CTSQ","description":"La corporation des th\u00e9rapeutes du sport du Qu\u00e9bec","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ctsq.qc.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/pages\/16759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/comments?post=16759"}],"version-history":[{"count":1,"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/pages\/16759\/revisions"}],"predecessor-version":[{"id":16760,"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/pages\/16759\/revisions\/16760"}],"wp:attachment":[{"href":"https:\/\/ctsq.qc.ca\/en\/wp-json\/wp\/v2\/media?parent=16759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}